{"id":4206,"date":"2024-06-20T19:00:36","date_gmt":"2024-06-20T19:00:36","guid":{"rendered":"https:\/\/sftl.nta-srv.be\/?p=4206"},"modified":"2025-01-27T11:06:21","modified_gmt":"2025-01-27T11:06:21","slug":"sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds","status":"publish","type":"post","link":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/","title":{"rendered":"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der SFTL legt gro\u00dfen Wert auf die Gesundheit aller, die in der Branche arbeiten. Im Fall eines Krankenhausaufenthalts k\u00f6nnen die Arbeiter der Transport- und Logistikbranche ihre&nbsp;<strong>sektorale Krankenhausversicherung<\/strong>&nbsp;in Anspruch nehmen. Wenn sich Arbeiter aus privaten oder beruflichen Gr\u00fcnden im Ausland aufhalten, stehen ihnen zudem Beistandsleistungen zu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Transport- und Logistikbranche sorgt auch dann f\u00fcr ihre Arbeiter, wenn sie im Ruhestand sind. Um zus\u00e4tzlich zur gesetzlichen Altersversorgung eine&nbsp;<strong>erg\u00e4nzende Pension<\/strong>&nbsp;gew\u00e4hren zu k\u00f6nnen, hat der SFTL den Pensionsfonds \u201ePensio TL\u201c eingerichtet. Dieser Pensionsplan wird \u00fcber einen Arbeitgeberbeitrag der Arbeitgeber dieser Branche finanziert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noch Fragen?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"mailto:hospitalisation@fstl.be\" target=\"_blank\">hospitalisation@fstl.be<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"mailto:pensiotl@fstl.be\" target=\"_blank\">pensiotl@fstl.be<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der SFTL legt gro\u00dfen Wert auf die Gesundheit aller, die in der Branche arbeiten. Im Fall eines Krankenhausaufenthalts k\u00f6nnen die Arbeiter der Transport- und Logistikbranche ihre&nbsp;sektorale Krankenhausversicherung&nbsp;in Anspruch nehmen. Wenn sich Arbeiter aus privaten oder beruflichen Gr\u00fcnden im Ausland aufhalten, stehen ihnen zudem Beistandsleistungen zu. Die Transport- und Logistikbranche sorgt auch dann f\u00fcr ihre Arbeiter, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"post-template-version4.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-4206","post","type-post","status-publish","format-standard","hentry","category-umweltschutz-wohlbefinden-und-machbare-arbeit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sektorale Krankenhausversicherung und sektoraler Pensionsfonds - SFTL - Sociaal Fonds Transport en Logistiek<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds - SFTL - Sociaal Fonds Transport en Logistiek\" \/>\n<meta property=\"og:description\" content=\"Der SFTL legt gro\u00dfen Wert auf die Gesundheit aller, die in der Branche arbeiten. Im Fall eines Krankenhausaufenthalts k\u00f6nnen die Arbeiter der Transport- und Logistikbranche ihre&nbsp;sektorale Krankenhausversicherung&nbsp;in Anspruch nehmen. Wenn sich Arbeiter aus privaten oder beruflichen Gr\u00fcnden im Ausland aufhalten, stehen ihnen zudem Beistandsleistungen zu. Die Transport- und Logistikbranche sorgt auch dann f\u00fcr ihre Arbeiter, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/\" \/>\n<meta property=\"og:site_name\" content=\"SFTL - Sociaal Fonds Transport en Logistiek\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T19:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T11:06:21+00:00\" \/>\n<meta name=\"author\" content=\"Tim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/\"},\"author\":{\"name\":\"Tim\",\"@id\":\"https:\/\/sftl.be\/#\/schema\/person\/1643f9f4621f179a5e2df0fc7f23bd4f\"},\"headline\":\"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds\",\"datePublished\":\"2024-06-20T19:00:36+00:00\",\"dateModified\":\"2025-01-27T11:06:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/\"},\"wordCount\":117,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sftl.be\/#organization\"},\"articleSection\":[\"Umweltschutz, Wohlbefinden und machbare Arbeit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/\",\"url\":\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/\",\"name\":\"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds - SFTL - Sociaal Fonds Transport en Logistiek\",\"isPartOf\":{\"@id\":\"https:\/\/sftl.be\/#website\"},\"datePublished\":\"2024-06-20T19:00:36+00:00\",\"dateModified\":\"2025-01-27T11:06:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sftl.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sftl.be\/#website\",\"url\":\"https:\/\/sftl.be\/\",\"name\":\"SFTL\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sftl.be\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sftl.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sftl.be\/#organization\",\"name\":\"SFTL\",\"url\":\"https:\/\/sftl.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/sftl.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sftl.be\/wp-content\/uploads\/2025\/01\/sftl-logo.png\",\"contentUrl\":\"https:\/\/sftl.be\/wp-content\/uploads\/2025\/01\/sftl-logo.png\",\"width\":1261,\"height\":594,\"caption\":\"SFTL\"},\"image\":{\"@id\":\"https:\/\/sftl.be\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/sftl.be\/#\/schema\/person\/1643f9f4621f179a5e2df0fc7f23bd4f\",\"name\":\"Tim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2d28bc06a3bf7c15d474b504e53fb0cf57f5d13fd9ccf2499b658322fe5ce30e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2d28bc06a3bf7c15d474b504e53fb0cf57f5d13fd9ccf2499b658322fe5ce30e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2d28bc06a3bf7c15d474b504e53fb0cf57f5d13fd9ccf2499b658322fe5ce30e?s=96&d=mm&r=g\",\"caption\":\"Tim\"},\"url\":\"https:\/\/sftl.be\/de\/author\/tim\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds - SFTL - Sociaal Fonds Transport en Logistiek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/","og_locale":"de_DE","og_type":"article","og_title":"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds - SFTL - Sociaal Fonds Transport en Logistiek","og_description":"Der SFTL legt gro\u00dfen Wert auf die Gesundheit aller, die in der Branche arbeiten. Im Fall eines Krankenhausaufenthalts k\u00f6nnen die Arbeiter der Transport- und Logistikbranche ihre&nbsp;sektorale Krankenhausversicherung&nbsp;in Anspruch nehmen. Wenn sich Arbeiter aus privaten oder beruflichen Gr\u00fcnden im Ausland aufhalten, stehen ihnen zudem Beistandsleistungen zu. Die Transport- und Logistikbranche sorgt auch dann f\u00fcr ihre Arbeiter, [&hellip;]","og_url":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/","og_site_name":"SFTL - Sociaal Fonds Transport en Logistiek","article_published_time":"2024-06-20T19:00:36+00:00","article_modified_time":"2025-01-27T11:06:21+00:00","author":"Tim","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tim","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#article","isPartOf":{"@id":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/"},"author":{"name":"Tim","@id":"https:\/\/sftl.be\/#\/schema\/person\/1643f9f4621f179a5e2df0fc7f23bd4f"},"headline":"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds","datePublished":"2024-06-20T19:00:36+00:00","dateModified":"2025-01-27T11:06:21+00:00","mainEntityOfPage":{"@id":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/"},"wordCount":117,"commentCount":0,"publisher":{"@id":"https:\/\/sftl.be\/#organization"},"articleSection":["Umweltschutz, Wohlbefinden und machbare Arbeit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/","url":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/","name":"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds - SFTL - Sociaal Fonds Transport en Logistiek","isPartOf":{"@id":"https:\/\/sftl.be\/#website"},"datePublished":"2024-06-20T19:00:36+00:00","dateModified":"2025-01-27T11:06:21+00:00","breadcrumb":{"@id":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sftl.be\/de\/interesse-an-der-branche\/umweltschutz-wohlbefinden-und-machbare-arbeit\/sektorale-krankenhausversicherung-und-sektoraler-pensionsfonds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sftl.be\/"},{"@type":"ListItem","position":2,"name":"Sektorale Krankenhausversicherung und sektoraler Pensionsfonds"}]},{"@type":"WebSite","@id":"https:\/\/sftl.be\/#website","url":"https:\/\/sftl.be\/","name":"SFTL","description":"","publisher":{"@id":"https:\/\/sftl.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sftl.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sftl.be\/#organization","name":"SFTL","url":"https:\/\/sftl.be\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sftl.be\/#\/schema\/logo\/image\/","url":"https:\/\/sftl.be\/wp-content\/uploads\/2025\/01\/sftl-logo.png","contentUrl":"https:\/\/sftl.be\/wp-content\/uploads\/2025\/01\/sftl-logo.png","width":1261,"height":594,"caption":"SFTL"},"image":{"@id":"https:\/\/sftl.be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sftl.be\/#\/schema\/person\/1643f9f4621f179a5e2df0fc7f23bd4f","name":"Tim","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/2d28bc06a3bf7c15d474b504e53fb0cf57f5d13fd9ccf2499b658322fe5ce30e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d28bc06a3bf7c15d474b504e53fb0cf57f5d13fd9ccf2499b658322fe5ce30e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d28bc06a3bf7c15d474b504e53fb0cf57f5d13fd9ccf2499b658322fe5ce30e?s=96&d=mm&r=g","caption":"Tim"},"url":"https:\/\/sftl.be\/de\/author\/tim\/"}]}},"_links":{"self":[{"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/posts\/4206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/comments?post=4206"}],"version-history":[{"count":3,"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/posts\/4206\/revisions"}],"predecessor-version":[{"id":5499,"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/posts\/4206\/revisions\/5499"}],"wp:attachment":[{"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/media?parent=4206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/categories?post=4206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sftl.be\/de\/wp-json\/wp\/v2\/tags?post=4206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}